{"id":16341,"count":10,"description":"","link":"https:\/\/gogotick.com\/en\/city\/corinth\/","name":"Corinth","slug":"corinth","taxonomy":"ciudad","parent":16204,"meta":[],"_links":{"self":[{"href":"https:\/\/gogotick.com\/en\/wp-json\/wp\/v2\/ciudad\/16341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gogotick.com\/en\/wp-json\/wp\/v2\/ciudad"}],"about":[{"href":"https:\/\/gogotick.com\/en\/wp-json\/wp\/v2\/taxonomies\/ciudad"}],"up":[{"embeddable":true,"href":"https:\/\/gogotick.com\/en\/wp-json\/wp\/v2\/ciudad\/16204"}],"wp:post_type":[{"href":"https:\/\/gogotick.com\/en\/wp-json\/wp\/v2\/lugares?ciudad=16341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}